{"id":78792,"date":"2026-05-12T00:00:00","date_gmt":"2026-05-11T22:00:00","guid":{"rendered":"https:\/\/visitacostadamorte.com\/?p=78792"},"modified":"2026-02-27T10:05:49","modified_gmt":"2026-02-27T09:05:49","slug":"mens-terra-de-monxes-e-nobres","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/blog\/mens-terra-de-monxes-e-nobres","title":{"rendered":"MENS, TERRA DE MONXES E NOBRES"},"content":{"rendered":"\n<p>A parroquia de Santiago de Mens, situada a uns 6 km da vila de Malpica, seguindo a estrada DP-4307 cara a Ponteceso, conserva dous dos edificios medievais m\u00e1is salientables da comarca de Berganti\u00f1os: a igrexa parroquial e as torres dos Altamira, un valioso patrimonio hist\u00f3rico para goce do viaxeiro que se achegue \u00e1 Costa da Morte.<\/p>\n\n\n\n<p>A igrexa de Santiago de Mens formou parte dun antigo mosteiro beneditino, do que hai noticias desde o s\u00e9culo X. O templo conserva boa parte da s\u00faa estrutura rom\u00e1nica do s\u00e9culo XII, que se amosa nas tres \u00e1bsidas, na porta sur e no muro norte. A fachada, que substitu\u00edu \u00e1 anterior, constru\u00eduse a finais do s\u00e9culo XIX. O que m\u00e1is chama a atenci\u00f3n desta edificaci\u00f3n \u00e9 a colecci\u00f3n de figuras de animais e humanas representadas nos canzorros das \u00e1bsidas e do muro norte, pola s\u00faa expresi\u00f3n e postura.<\/p>\n\n\n\n<p>A fortaleza de Mens, situada ao leste da igrexa, pertenceu \u00e1 poderosa familia dos Moscoso, condes de Altamira, que dominaron gran parte das terras da Costa da Morte. Neste castelo, igual que nos de Vimianzo e Ferreira, Bernal E\u00e1ns de Moscoso mantivo preso ao arcebispo compostel\u00e1n Alonso de Fonseca II entre os anos 1465 e 1466.<\/p>\n\n\n\n<p>Despois de ser derrubado na revolta irmandi\u00f1a de 1467, Lopo S\u00e1nchez de Moscoso I, conde de Altamira, mandou reconstru\u00edr a fortaleza, que permaneceu en mans desta familia ata 1872. Logo ser\u00eda adquirida pola familia Abelenda de Bu\u00f1o, que constru\u00edu a vivenda que se sit\u00faa no interior do recinto. Despois de permanecer en ru\u00ednas durante moitos anos, un descendente desta familia adquiriu a propiedade de todo o conxunto e rehabilitouno como vivenda particular.<\/p>\n\n\n\n<p>Entre d\u00faas construci\u00f3ns hist\u00f3ricas tan pr\u00f3ximas coma estas non pod\u00eda faltar unha lenda que as unira. C\u00f3ntase que un conde que habitaba na fortaleza raptou unha moza da aldea e que a prendeu no interior do castelo. Os veci\u00f1os, ante tal feito, xunt\u00e1ronse e decidiron asaltar as torres para liberar a rapaza. O conde, cando se viu acurralado, intentou fuxir a trav\u00e9s do t\u00fanel que comunicaba o castelo coa igrexa, pero os veci\u00f1os prenderon lume nas bocas do mesmo e o nobre morreu no interior. Logo, liberaron a moza. Desde aquela, o trigo que se sementa por onde pasa o t\u00fanel medra menos e marelece m\u00e1is axi\u00f1a. Por este motivo, aquel lugar se co\u00f1ece polo nome do Trigal Maldito.<\/p>\n\n\n\n<p>Desde Mens, temos a oportunidade de visitar punta Nariga, seguindo unha pista que atravesa a aldea e leva a esa extraordinaria paraxe. Al\u00ed no ano 1994 constru\u00eduse un maxestoso faro, unha obra proxectada polo arquitecto pontevedr\u00e9s C\u00e9sar Portela, quen se propuxo levantar unha construci\u00f3n s\u00f3lida e de gran beleza, integrada no marco gran\u00edtico da zona. A obra estrut\u00farase en tres corpos. O primeiro constitu\u00eddo por unha plataforma triangular, simbolizando unha embarcaci\u00f3n. Un segundo, con forma prism\u00e1tica tam\u00e9n triangular, para acoller os servizos do faro e, ao mesmo tempo, facer a funci\u00f3n de miradoiro da paisaxe. E un terceiro, a torre cil\u00edndrica que sustenta a lanterna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mira de preto Malpica De Berganti\u00f1os a trav\u00e9s de \u201cMENS, TERRA DE MONXES E NOBRES\u201d. M\u00e1is ca unha descrici\u00f3n: \u00e9 unha forma de entrar no lugar antes de pisalo. Pista: f\u00edxate en monjes.<\/p>\n","protected":false},"author":11,"featured_media":76828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"MENS, TERRA DE MONXES E NOBRES - Costa da Morte","description":"Mira de preto Malpica De Berganti\u00f1os a trav\u00e9s de \u201cMENS, TERRA DE MONXES E NOBRES\u201d. M\u00e1is ca unha descrici\u00f3n: \u00e9 unha forma de entrar no lugar antes de pisalo. Pis"},"page_builder":"","footnotes":""},"categories":[651],"tags":[1355,1320],"class_list":["post-78792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-malpica-de-bergantinos","tag-naturalmente-unica"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=78792"}],"version-history":[{"count":2,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78792\/revisions"}],"predecessor-version":[{"id":79253,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78792\/revisions\/79253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/76828"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=78792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=78792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=78792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}