{"id":78764,"date":"2026-03-21T00:00:00","date_gmt":"2026-03-20T23:00:00","guid":{"rendered":"https:\/\/visitacostadamorte.com\/?p=78764"},"modified":"2026-03-21T10:10:24","modified_gmt":"2026-03-21T09:10:24","slug":"torres-do-allo-un-dos-primeiros-pazos-de-galicia","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/blog\/torres-do-allo-un-dos-primeiros-pazos-de-galicia","title":{"rendered":"TORRES DO ALLO, UN DOS PRIMEIROS PAZOS DE GALICIA"},"content":{"rendered":"\n<p>Moi preto da vila de Baio, no km 55 da estrada C-552 da Coru\u00f1a a Fisterra, sit\u00faase o <strong><a href=\"https:\/\/visitacostadamorte.com\/gl\/post\/pazo-torres-do-allo\" target=\"_blank\" rel=\"noopener\" title=\"Pazo Torres do Allo\">pazo das Torres do Allo<\/a><\/strong>, unha das m\u00e1is significativas construci\u00f3ns deste tipo de vivenda de Galicia. Ao longo da historia esta casa do Allo sufriu poucas modificaci\u00f3ns porque se mantivo sempre en mans da mesma familia, os Rioboo, ori\u00fanda da torre da Penela.<\/p>\n\n\n\n<p>Ata a investigaci\u00f3n levada cabo polo historiador Jos\u00e9 A. S\u00e1nchez Garc\u00eda, cr\u00edase que toda a construci\u00f3n era da mesma \u00e9poca, pero a ra\u00edz desa nova informaci\u00f3n s\u00f3ubose que a torre norte edificouse entre os anos 1490 e 1512, a iniciativa de Alfonso G\u00f3mez de Rioboo Villardefrancos, mentres que a torre sur e o corpo central levantar\u00edanse entre 1669 e 1685 por decisi\u00f3n de G\u00f3mez de Rioboo e Seixas e a s\u00faa dona Jacinta de Luces Caama\u00f1o, que decidiron conservar as formas do estilo g\u00f3tico tard\u00edo da torre primitiva.<\/p>\n\n\n\n<p>As <strong><a href=\"https:\/\/visitacostadamorte.com\/gl\/post\/pazo-torres-do-allo\" target=\"_blank\" rel=\"noopener\" title=\"Pazo Torres do Allo\">torres<\/a><\/strong> son case sim\u00e9tricas. Na parte baixa \u00e1brese unha porta con arco de medio punto con grandes doelas, propio da arquitectura do s\u00e9culo XVI. O segundo andar \u00e9 o que mostra unha maior riqueza decorativa nos elementos da fachada: fiestra con arcos xeminados, portavent\u00e1, con varanda na torre norte e balc\u00f3n, na sur. Todo o conxunto enmarcado por un arco mixtil\u00edneo. No terceiro andar simplemente se abre unha fiestra.<\/p>\n\n\n\n<p>Nos escudos aparecen os s\u00edmbolos das familias que emparentaron cos Rioboo e habitaron esta casa fidalga. A torre envolta en silvas, dos Rioboo; o pi\u00f1eiro e as lanzas, dos Caama\u00f1o; as cinco pombas, correspondentes aos Seixas; os dous lagartos baixo unha lousa, dos Losada; e as cinco follas de figueira, que identifican aos Figueroa.<\/p>\n\n\n\n<p>O corpo central componse de d\u00faas alturas e tellado a d\u00faas augas, no que destaca unha robusta cheminea. Na planta baixa \u00e1brense tres portas e na planta superior m\u00f3stranse seis fiestras rectangulares con mainel. Na cornixa resaltan as figuras das g\u00e1rgolas.<\/p>\n\n\n\n<p>Na primeira metade do s\u00e9culo XX deixaron de habitar o pazo os propietarios e fix\u00e9rono os apoderados, e xa na segunda metade, quedou deshabitado. A <a href=\"https:\/\/www.dacoruna.gal\/portada\" target=\"_blank\" rel=\"noopener\" title=\"Deputaci\u00f3n da Coru\u00f1a\">Deputaci\u00f3n da Coru\u00f1a<\/a>, consciente do valor hist\u00f3rico e arquitect\u00f3nico do edificio, chegou a un acordo coa familia L\u00f3pez-Rioboo e adquiriuno en 1998. Dous anos despois comezaron as obras de rehabilitaci\u00f3n e abriuse ao p\u00fablico en 2005, xestionado polo <a href=\"https:\/\/concellodezas.gal\/\" title=\"Concello de Zas\">Concello de Zas<\/a>. No interior m\u00f3strase como era a vida rural na \u00e9poca dos pazos, a li\u00f1axe da familia Rioboo e informaci\u00f3n sobre outros pazos da Costa da Morte. Acolle tam\u00e9n actividades culturais.<\/p>\n\n\n\n<p>A uns 200 m do pazo sit\u00faase a <a href=\"https:\/\/visitacostadamorte.com\/gl\/post\/igrexa-de-san-pedro-do-allo\" target=\"_blank\" rel=\"noopener\" title=\"Igrexa de San Pedro do Allo\">igrexa parroquial de San Pedro do Allo<\/a>, que actuou como capela particular dos Rioboo, na que se soterraron varios dos seus membros. Conserva unha interesante fachada-retablo renacentista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ach\u00e9gate a Zas a trav\u00e9s de \u201cTORRES DO ALLO, UN DOS PRIMEIROS PAZOS DE GALICIA\u201d. Comeza por este cap\u00edtulo e entender\u00e1s mellor o territorio antes de visitalo. Pista: f\u00edxate en galicia.<\/p>\n","protected":false},"author":11,"featured_media":77963,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"TORRES DO ALLO, UN DOS PRIMEIROS PAZOS DE GALICIA - Costa da Morte","description":"Ach\u00e9gate a Zas a trav\u00e9s de \u201cTORRES DO ALLO, UN DOS PRIMEIROS PAZOS DE GALICIA\u201d. Comeza por este cap\u00edtulo e entender\u00e1s mellor o territorio antes de visitalo. Pis"},"page_builder":"","footnotes":""},"categories":[651],"tags":[1320,145],"class_list":["post-78764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-naturalmente-unica","tag-zas-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=78764"}],"version-history":[{"count":3,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78764\/revisions"}],"predecessor-version":[{"id":80116,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/78764\/revisions\/80116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/77963"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=78764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=78764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=78764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}