{"id":64041,"date":"2024-10-16T12:22:03","date_gmt":"2024-10-16T10:22:03","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/?p=64041"},"modified":"2024-10-16T13:33:11","modified_gmt":"2024-10-16T11:33:11","slug":"presentacion-candidaturas-iv-encontro-turismo-costa-da-morte","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/presentacion-candidaturas-iv-encontro-turismo-costa-da-morte","title":{"rendered":"Aberto o prazo de presentaci\u00f3n de candidaturas para albergar o IV Encontro Anual de Turismo da Costa da Morte"},"content":{"rendered":"\n<p><strong>ZAS, 03\/09\/2024.&nbsp;<\/strong>A CMAT abre o prazo de presentaci\u00f3n de candidaturas para acoller o Encontro de Turismo Anual da Costa da Morte, que celebra a s\u00faa cuarta edici\u00f3n o d\u00eda&nbsp;<strong>12 de novembro entre as 17:30 e as 20 horas<\/strong>.<\/p>\n\n\n\n<p>As empresas do sector tur\u00edstico da Costa da Morte que te\u00f1an interese en acoller este evento&nbsp;<strong>poden presentar a s\u00faa candidatura<\/strong>&nbsp;ata o&nbsp;<strong>17 de setembro<\/strong>.<\/p>\n\n\n\n<p>Este importante evento est\u00e1 enmarcado dentro das actividades inclu\u00eddas no convenio de colaboraci\u00f3n que a CMAT e Turismo de Galicia asinar\u00e1n neste mes de setembro. O encontro tam\u00e9n conta co apoio da Deputaci\u00f3n da Coru\u00f1a. Como novidades na edici\u00f3n deste 2024 do Encontro Anual de Turismo, a organizaci\u00f3n po\u00f1er\u00e1 todo o seu esforzo para levar adiante unha exposici\u00f3n de artesan\u00eda. Ademais, durante o evento&nbsp;<strong>tam\u00e9n se expo\u00f1er\u00e1n as fotograf\u00edas finalistas do&nbsp;<\/strong><a href=\"https:\/\/www.visitacostadamorte.com\/es\/cmat\/bases-legales-concurso-naturalmente-salvaxe-2024-es\"><strong>I Concurso Fotogr\u00e1fico Costa da Morte Naturalmente Salvaxe<\/strong><\/a>, que contin\u00faa aberto \u00e1 participaci\u00f3n do p\u00fablico ata o 30 de outubro \u00e1s 23:59h.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Un evento cada vez m\u00e1is asentado<\/strong><\/h4>\n\n\n\n<p>O Encontro Anual de Turismo da Costa da Morte ten como obxectivo ser un punto de encontro dos axentes p\u00fablicos e privados do territorio. Axentes que traballan cada d\u00eda para mellorar o destino tur\u00edstico da Costa da Morte. A andadura deste encontro comezou no ano 2021 no Parador Costa da Morte, en Mux\u00eda. As seguintes edici\u00f3ns foron en Costa Cai\u00f3n (Cai\u00f3n, A Laracha) e na Torre de Laxe (Laxe).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>O encontro deste ano 2024<\/strong><\/h4>\n\n\n\n<p>O IV Encontro Anual de Turismo da Costa da Morte aspira a ser un espazo para po\u00f1er en com\u00fan os \u00e9xitos acadados neste ano, intercambiar novas ideas e propostas e facer crecer o xeodestino cunha visi\u00f3n sostible a nivel econ\u00f3mico e social.<\/p>\n\n\n\n<p>As candidaturas interesadas ter\u00e1n que cumplir unha serie de requisitos, entre os que se atopan os seguintes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estar localizado na Costa da Morte<\/li>\n\n\n\n<li>Aforo m\u00ednimo de 150 persoas (valorable ata 200)<\/li>\n\n\n\n<li>Experiencia neste tipo de eventos<\/li>\n\n\n\n<li>Dispo\u00f1ibilidade de datas e horas<\/li>\n<\/ul>\n\n\n\n<p>O&nbsp;<strong>resto de requisitos e as caracter\u00edsticas espec\u00edficas do evento&nbsp;<\/strong>p\u00f3dense consultar&nbsp;<a href=\"https:\/\/drive.google.com\/uc?id=1dO0pAekujuSuN3JXvWKJkFJvHN3DnKuu&amp;export=download\">na web da CMAT a trav\u00e9s da seguinte ligaz\u00f3n<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Presentaci\u00f3n das candidaturas<\/strong><\/h4>\n\n\n\n<p>Para os establecementos interesados, o&nbsp;<strong>prazo de presentaci\u00f3n das candidaturas remata o 17 de setembro de 2024<\/strong>. A presentaci\u00f3n da candidatura farase a trav\u00e9s do env\u00edo&nbsp;<a href=\"https:\/\/drive.google.com\/uc?id=12_uYOUeGFbLqYyO5Fu6J1jFtgZ3u9C9Y&amp;export=download\">deste anexo descargable que deber\u00e1 ser enviado coa documentaci\u00f3n complementaria<\/a>&nbsp;que cada establecemento considere necesario e que poida axudar \u00e1 CMAT a realizar as valoraci\u00f3ns que estime oportunas ao seguinte correo electr\u00f3nico:&nbsp;<a href=\"mailto:admincmat@visitacostadamorte.com\">admincmat@visitacostadamorte.com<\/a>.<\/p>\n\n\n\n<p>Unha vez valoradas as candidaturas recibidas,&nbsp;<strong>a CMAT contactar\u00e1 coas empresas<\/strong>&nbsp;para analizar os diferentes aspectos das s\u00faas propostas e seleccionar a m\u00e1is adecuada para o evento. Neste sentido e na medida do posible, procurarase organizar o encontro nun concello que non acollera o evento previamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este ano, o encontro organizado pola CMAT co cofinanciamento de Turismo de Galicia e o apoio da Deputaci\u00f3n da Coru\u00f1a, celebrarase o 12 de novembro O Encontro Anual de Turismo \u00e9 unha das actividades enmarcadas dentro do convenio entre a CMAT e Turismo de Galicia, que ser\u00e1 asinado neste mes de setembro<\/p>\n","protected":false},"author":7,"featured_media":64038,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"Aberto o prazo de presentaci\u00f3n de candidaturas para albergar o IV Encontro Anual de Turismo da Costa da Morte - Costa da Morte","description":"Este ano, o encontro organizado pola CMAT co cofinanciamento de Turismo de Galicia e o apoio da Deputaci\u00f3n da Coru\u00f1a, celebrarase o 12 de novembro O Encontro An"},"page_builder":"","footnotes":""},"categories":[106],"tags":[531],"class_list":["post-64041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-encontro-de-turismo"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/64041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=64041"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/64041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/64038"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=64041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=64041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=64041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}