{"id":4790,"date":"2017-09-27T00:00:00","date_gmt":"2017-09-26T22:00:00","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/sin-categorizar\/coastering-e-descensos"},"modified":"2024-11-06T07:07:24","modified_gmt":"2024-11-06T06:07:24","slug":"coastering-e-descensos","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/coastering-e-descensos","title":{"rendered":"Coastering e descensos"},"content":{"rendered":"<p>O coasteering, tam\u00e9n co\u00f1ecido como coastering, \u00e9 un deporte de aventura que consiste en realizar un percorrido costeiro combinando sendeirismo, saltos de altura \u00e1 auga, exploraci\u00f3n de covas terrestres, mergullo, escalada de traves\u00eda, r\u00e1pel e ponte de corda entre outras. Consider\u00e1ndose se unha modalidade do trekking.\ufffd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O coasteering, tam\u00e9n co\u00f1ecido como coastering, \u00e9 un deporte de aventura que consiste en realizar un percorrido costeiro combinando sendeirismo, saltos de altura \u00e1 auga, exploraci\u00f3n de covas terrestres, mergullo, escalada de traves\u00eda, r\u00e1pel e ponte de corda entre outras. Consider\u00e1ndose se unha modalidade do trekking.\ufffd<\/p>\n","protected":false},"author":7,"featured_media":2766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"Coastering e descensos - Costa da Morte","description":"O coasteering, tam\u00e9n co\u00f1ecido como coastering, \u00e9 un deporte de aventura que consiste en realizar un percorrido costeiro combinando sendeirismo, saltos de altura"},"page_builder":"","footnotes":""},"categories":[106],"tags":[126],"class_list":["post-4790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-dumbria-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=4790"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/2766"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=4790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=4790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=4790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}