{"id":4782,"date":"2018-01-23T00:00:00","date_gmt":"2018-01-22T23:00:00","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/sin-categorizar\/contacontos-musica-xogos-e-obradoiros-na-programacion-do-primeiro-trimestre-do-apego-en-carballo"},"modified":"2024-11-06T07:07:16","modified_gmt":"2024-11-06T06:07:16","slug":"contacontos-musica-xogos-e-obradoiros-na-programacion-do-primeiro-trimestre-do-apego-en-carballo","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/contacontos-musica-xogos-e-obradoiros-na-programacion-do-primeiro-trimestre-do-apego-en-carballo","title":{"rendered":"Contacontos, m\u00fasica, xogos e obradoiros, na programaci\u00f3n do primeiro trimestre do Apego en Carballo."},"content":{"rendered":"<p>O programa Apego non naceu en Carballo por casualidade, sen\u00f3n porque representa un xeito de entender a pol\u00edtica ling\u00fc\u00edstica: \u201cHai pol\u00edticas que \u00e1 forza te\u00f1en que ser transversais, e as pol\u00edticas de promoci\u00f3n e socializaci\u00f3n da lingua galega \u00e1 forza te\u00f1en que ser transversais\u201d, sinala o concelleiro de Normalizaci\u00f3n Ling\u00fc\u00edstica, Xos\u00e9 Regueira. El foi un dos encargados de presentar hoxe, xunto co normalizador ling\u00fc\u00edstico do Concello, Nel Vidal, e o alcalde, Evencio Ferrero, o programa de actividades con Apego que se desenvolver\u00e1n ao longo deste primeiro trimestre do ano, a partir de hoxe mesmo. Pero nesta ocasi\u00f3n tam\u00e9n nos convidan a participar prest\u00e1ndonos a s\u00faa imaxe Alberto e Xo\u00e1n, pai e fillo, usuarios do programa.<\/p>\n<h4><a href=\"https:\/\/www.visitacostadamorte.com\/archivos\/pdf\/Programa_Apego_Carballo_Inverno_2018.pdf\"><i class=\"fa fa-file-pdf-o\"><\/i>\u00a0Descargar programa<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>O programa Apego non naceu en Carballo por casualidade, sen\u00f3n porque representa un xeito de entender a pol\u00edtica ling\u00fc\u00edstica: \u201cHai pol\u00edticas que \u00e1 forza te\u00f1en que ser transversais, e as pol\u00edticas de promoci\u00f3n e socializaci\u00f3n da lingua galega \u00e1 forza te\u00f1en que ser transversais\u201d, sinala o concelleiro de Normalizaci\u00f3n Ling\u00fc\u00edstica, Xos\u00e9 Regueira. El foi un [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"Contacontos, m\u00fasica, xogos e obradoiros, na programaci\u00f3n do primeiro trimestre do Apego en Carballo. - Costa da Morte","description":"O programa Apego non naceu en Carballo por casualidade, sen\u00f3n porque representa un xeito de entender a pol\u00edtica ling\u00fc\u00edstica: \u201cHai pol\u00edticas que \u00e1 forza te\u00f1en qu"},"page_builder":"","footnotes":""},"categories":[106],"tags":[113],"class_list":["post-4782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-carballo-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=4782"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/2734"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=4782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=4782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=4782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}