{"id":4781,"date":"2018-01-23T00:00:00","date_gmt":"2018-01-22T23:00:00","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/sin-categorizar\/o-concello-de-zas-reparte-2500-euros-na-iii-mostra-de-teatro-labarta-posse"},"modified":"2024-11-06T07:07:16","modified_gmt":"2024-11-06T06:07:16","slug":"o-concello-de-zas-reparte-2500-euros-na-iii-mostra-de-teatro-labarta-posse","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/o-concello-de-zas-reparte-2500-euros-na-iii-mostra-de-teatro-labarta-posse","title":{"rendered":"O Concello de Zas reparte 2.500 euros na III Mostra de Teatro &#8220;Labarta Posse&#8221;"},"content":{"rendered":"<p>Por terceiro ano consecutivo, o Concello de Zas organiza a\u00a0<strong>III Mostra de Teatro Afeccionado \u201cLabarta Pose\u201d<\/strong>\u00a0coa que pretende, por unha parte, fomentar a cultura especialmente no eido das artes esc\u00e9nicas e, por outra, favorecer o teatro feito en Galicia e en galego. Nesta edici\u00f3n, incorporouse o nome de Labarta Pose para conmemorar a figura do escritor bai\u00e9s.\u00a0 No certame poder\u00e1n participar todos os grupos ou compa\u00f1\u00edas de teatro da comunidade e, como novidade, este ano est\u00e1 aberto tam\u00e9n a persoas naturais ou xur\u00eddicas tanto p\u00fablicas como privadas.<\/p>\n<p><strong>Inscrici\u00f3ns e premios<\/strong><\/p>\n<p>Unha vez que se publiquen as bases do concurso no Bolet\u00edn Oficial da Provincia \u2013 BOP -, que ser\u00e1 nos vindeiros d\u00edas, queda aberto o prazo de inscrici\u00f3n que se prolongar\u00e1 at\u00e9 o vindeiro d\u00eda 1 de marzo. Para participar \u00e9 necesario anotarse presentando a documentaci\u00f3n pertinente as\u00ed como os anexos que acompa\u00f1an \u00e1s Bases debidamente cumprimentadas.\u00a0O xurado, composto por membros do Concello de Zas e do grupo de teatro Badius, seleccionar\u00e1 os cinco espect\u00e1culos finalistas que ser\u00e1n os que se representen os d\u00edas\u00a0<strong>21 e 28 de abril e 5, 12 e 19 de maio<\/strong>\u00a0distribu\u00eddas entre o auditorio do pavill\u00f3n de Baio e o auditorio da Casa do Concello de Zas. A entrega de premios ter\u00e1 lugar o domingo 27 de maio.<\/p>\n<p>Outra das novidades desta terceira edici\u00f3n son os premios. Nesta ocasi\u00f3n,\u00a0<strong>o Concello de Zas destina 2.500\u20ac<\/strong>\u00a0que distribuir\u00e1 entre cada unha das cinco obras finalistas as cales recibir\u00e1n 500\u20ac. Tam\u00e9n haber\u00e1 premio para a mellor obra elixida polo xurado (trofeo e diploma acreditativo), premio ao mellor actor e \u00e1 mellor actriz (trofeo e diploma acreditativo) e premio \u00e1 mellor obra elixida polo xurado (trofeo e diploma acreditativo).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por terceiro ano consecutivo, o Concello de Zas organiza a\u00a0III Mostra de Teatro Afeccionado \u201cLabarta Pose\u201d\u00a0coa que pretende, por unha parte, fomentar a cultura especialmente no eido das artes esc\u00e9nicas e, por outra, favorecer o teatro feito en Galicia e en galego. Nesta edici\u00f3n, incorporouse o nome de Labarta Pose para conmemorar a figura do [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"O Concello de Zas reparte 2.500 euros na III Mostra de Teatro \"Labarta Posse\" - Costa da Morte","description":"Por terceiro ano consecutivo, o Concello de Zas organiza a\u00a0 III Mostra de Teatro Afeccionado \u201cLabarta Pose\u201d \u00a0coa que pretende, por unha parte, fomentar a cultur"},"page_builder":"","footnotes":""},"categories":[106],"tags":[145],"class_list":["post-4781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-zas-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=4781"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/2730"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=4781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=4781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=4781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}