{"id":4706,"date":"2018-05-19T00:00:00","date_gmt":"2018-05-18T22:00:00","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/sin-categorizar\/visita-da-delegacion-do-concello-frances-de-la-turballe-a-camarinas"},"modified":"2024-11-06T07:05:56","modified_gmt":"2024-11-06T06:05:56","slug":"visita-da-delegacion-do-concello-frances-de-la-turballe-a-camarinas","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/visita-da-delegacion-do-concello-frances-de-la-turballe-a-camarinas","title":{"rendered":"Visita da delegaci\u00f3n do concello franc\u00e9s de La Turballe a Camari\u00f1as"},"content":{"rendered":"<p style=\"text-align: justify;\">Do 23 ao 28 de maio estar\u00e1 en Camari\u00f1as unha delegaci\u00f3n do Concello franc\u00e9s de La Turballe. Preside esta delegaci\u00f3n o alcalde de La Turballe Jean Pierre Blancherau e a presidenta Dominique Floc\u00b4h da asociaci\u00f3n de irmandamento <i>La Turballe Cap Camari\u00f1as<\/i>. Dentro desta delegaci\u00f3n tam\u00e9n nos visitar\u00e1 unha embarcaci\u00f3n que realiza o recorrido por mar ata o porto deportivo do Club Na\u00fatico do noso concello por primeira vez.\u00a0<\/p>\n<p style=\"text-align: justify;\">A delegaci\u00f3n ten un programa moi intenso xa que durante a s\u00faa estancia tam\u00e9n se achegaran a co\u00f1ecer a Costa da Morte. As actividades en Camari\u00f1as concentrase na fin de semana do 25 ao 27 de maio e ten como obxectivo facilitar o co\u00f1ecemento mutuo das cidadan\u00edas e o tecido asociativo local e promover intercambios culturais, educativos, deportivos, tur\u00edsticos, social e econ\u00f3mico que afiance os lazos de amizade e cooperaci\u00f3n.\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Venres 25 de maio<\/strong>.\u00a0<\/p>\n<p style=\"text-align: justify;\">8:30 Sa\u00fado oficial ao grupo\u00a0<\/p>\n<p style=\"text-align: justify;\">9:00 Sa\u00edda do grupo para Costa da Morte. Visita guiada pola empresa local Vive a Costa da Morte\u00a0<\/p>\n<p style=\"text-align: justify;\">10:00 Visitas ao tecido industrial de Camari\u00f1as para o grupo de representantes do concello La Turballe\u00a0<\/p>\n<p style=\"text-align: justify;\">10:00 Visita a la empresa acu\u00edcola Stol Sea Farm\u00a0<\/p>\n<p style=\"text-align: justify;\">11:00 Visita a la conservera Cerdeimar y su museo de la conserva\u00a0<\/p>\n<p style=\"text-align: justify;\">16:00 Visita industria Gallego Pereira\u00a0<\/p>\n<p style=\"text-align: justify;\">17:30 Visita Escola de Palillo e asociaci\u00f3ns de palilleiras de Camari\u00f1as\u00a0<\/p>\n<p style=\"text-align: justify;\">19:00 Visita e intercambio coa directiva do Club Na\u00fatico de Camari\u00f1as\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e1bado 26 de maio<\/strong>.\u00a0<\/p>\n<p style=\"text-align: justify;\">08:30 Visita \u201cCami\u00f1ando por Camari\u00f1as\u201d guiada pola empresa local Vive a Costa da Morte\u00a0<\/p>\n<p style=\"text-align: justify;\">11:00 Acto de recepci\u00f3n oficial do Pleno municipal na Casa Consistorial. Acto que pecharase cunha actuaci\u00f3n do grupo folkl\u00f3rico de la Turballe e o Coro de Camari\u00f1as\u00a0<\/p>\n<p style=\"text-align: justify;\">12:00 Visita ao punto de informaci\u00f3n sobre La Turballe na Biblioteca. Presentaci\u00f3n da actividade o Berberecho Rebecho viaxa a La Turballe polos propios nenos que participaron. Intercambio de debuxos\u00a0<\/p>\n<p style=\"text-align: justify;\">12:30 \u201cOs sabores da nosa lingua\u201d intercambio gastrocultural. Plaza del Mercado. Actividade de promoci\u00f3n da lingua e a cultura galega realizada en colaboraci\u00f3n coa Conseller\u00eda de Educaci\u00f3n e Ordenaci\u00f3n Universitaria da Xunta de Galicia.<\/p>\n<p style=\"text-align: justify;\">17:00 Escola Baile Latino. Actuaci\u00f3n fin curso na Casa de Pedra\u00a0<\/p>\n<p style=\"text-align: justify;\">18:00 Visita guiada polas parroquias de Camari\u00f1as e ruta das mariscadoras.\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong>Domingo 27 de maio<\/strong>.\u00a0<\/p>\n<p style=\"text-align: justify;\">09:30 Sa\u00edda de la Carreira Oficial de bicicletas: \u201cBTT de Camari\u00f1as\u201d\u00a0<\/p>\n<p style=\"text-align: justify;\">11:00 Sa\u00edda do autob\u00fas para a festa Foxo dos Lobos dende a praza do Concello\u00a0<\/p>\n<p style=\"text-align: justify;\">11:30 Foxo dos Lobos: recreaci\u00f3n da batida del Foxo dos Lobos (participaci\u00f3n do p\u00fablico e a delegaci\u00f3n de La Turballe)\u00a0<\/p>\n<p style=\"text-align: justify;\">13:30 Comida campestre e m\u00fasica da Turballe e Camari\u00f1as\u00a0<\/p>\n<p style=\"text-align: justify;\">17:00h Actuaci\u00f3n da Escola de M\u00fasica de Camari\u00f1as na Casa de Pedra\u00a0<\/p>\n<p style=\"text-align: justify;\">21:00h Cea de gala.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do 23 ao 28 de maio estar\u00e1 en Camari\u00f1as unha delegaci\u00f3n do Concello franc\u00e9s de La Turballe. Preside esta delegaci\u00f3n o alcalde de La Turballe Jean Pierre Blancherau e a presidenta Dominique Floc\u00b4h da asociaci\u00f3n de irmandamento La Turballe Cap Camari\u00f1as. Dentro desta delegaci\u00f3n tam\u00e9n nos visitar\u00e1 unha embarcaci\u00f3n que realiza o recorrido por mar [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2433,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"Visita da delegaci\u00f3n do concello franc\u00e9s de La Turballe a Camari\u00f1as - Costa da Morte","description":"Do 23 ao 28 de maio estar\u00e1 en Camari\u00f1as unha delegaci\u00f3n do Concello franc\u00e9s de La Turballe. Preside esta delegaci\u00f3n o alcalde de La Turballe Jean Pierre Blanche"},"page_builder":"","footnotes":""},"categories":[106],"tags":[112],"class_list":["post-4706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-camarinas-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=4706"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/2433"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=4706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=4706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=4706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}