{"id":4617,"date":"2018-11-03T00:00:00","date_gmt":"2018-11-02T23:00:00","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/sin-categorizar\/abrese-o-prazo-para-presentar-webseries-ao-6-carballo-interplay"},"modified":"2024-11-06T06:59:19","modified_gmt":"2024-11-06T05:59:19","slug":"abrese-o-prazo-para-presentar-webseries-ao-6-carballo-interplay","status":"publish","type":"post","link":"https:\/\/visitacostadamorte.com\/gl\/novas\/abrese-o-prazo-para-presentar-webseries-ao-6-carballo-interplay","title":{"rendered":"\u00c1brese o prazo para presentar webseries ao 6\u00ba Carballo Interplay"},"content":{"rendered":"<p>A sexta edici\u00f3n do Festival de Contidos Dixitais Carballo Interplay, que se celebrar\u00e1 os d\u00edas 3, 4, 5 e 6 de abril de 2019, abre a inscrici\u00f3n para que todas aquelas persoas que o desexen presenten as s\u00faas webseries ou proxectos de webserie \u00e1 s\u00faa secci\u00f3n oficial, que repartir\u00e1 m\u00e1is de 5.000 euros en premios. Poden facelo dende hoxe mesmo e ata o 18 de febreiro a trav\u00e9s da web www.carballointerplay.com, de xeito gratu\u00edto.<\/p>\n<p>As webseries participantes, que deben ser producidas entre os anos 2017 e 2019 e ter un m\u00ednimo de 3 cap\u00edtulos emitidos no momento de inscrici\u00f3n, poden ser de calquera duraci\u00f3n, tem\u00e1tica, x\u00e9nero, de imaxe real ou de animaci\u00f3n, nacionais ou internacionais.<\/p>\n<p>Entre as webseries recibidas, un xurado composto por profesionais do sector audiovisual e da cultura, as\u00ed como de representantes de asociaci\u00f3ns profesionais relacionadas co sector premiar\u00e1 a mellor webserie, a mellor webserie internacional e a mellor webserie en versi\u00f3n orixinal en galego con 800 euros e trofeo, para cada categor\u00eda. As escollas do xurado novo e m\u00e1is do p\u00fablico levar\u00e1n 400 euros e trofeo, cada unha. Tam\u00e9n haber\u00e1 un premio ao mellor gui\u00f3n e un premio \u00e1 mellor direcci\u00f3n, dotados con 200 euros e trofeo. Finalmente, entregaranse cadanseu trofeo \u00e1 mellor actriz e ao mellor actor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sexta edici\u00f3n do Festival de Contidos Dixitais Carballo Interplay, que se celebrar\u00e1 os d\u00edas 3, 4, 5 e 6 de abril de 2019, abre a inscrici\u00f3n para que todas aquelas persoas que o desexen presenten as s\u00faas webseries ou proxectos de webserie \u00e1 s\u00faa secci\u00f3n oficial, que repartir\u00e1 m\u00e1is de 5.000 euros en premios. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"slim_seo":{"title":"\u00c1brese o prazo para presentar webseries ao 6\u00ba Carballo Interplay - Costa da Morte","description":"A sexta edici\u00f3n do Festival de Contidos Dixitais Carballo Interplay, que se celebrar\u00e1 os d\u00edas 3, 4, 5 e 6 de abril de 2019, abre a inscrici\u00f3n para que todas aqu"},"page_builder":"","footnotes":""},"categories":[106],"tags":[113],"class_list":["post-4617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novas","tag-carballo-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/comments?post=4617"}],"version-history":[{"count":0,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/posts\/4617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=4617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categories?post=4617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/tags?post=4617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}