{"id":63468,"date":"2024-05-23T11:06:54","date_gmt":"2024-05-23T09:06:54","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/post\/dolmen-de-parxubeira"},"modified":"2024-09-17T19:53:21","modified_gmt":"2024-09-17T17:53:21","slug":"dolmen-de-parxubeira","status":"publish","type":"contenido","link":"https:\/\/visitacostadamorte.com\/gl\/post\/dolmen-de-parxubeira","title":{"rendered":"Dolmen de Parxubeira"},"content":{"rendered":"\n<p>Polos restos arqueol\u00f3xicos atopados, podemos dicir que os primeiros mazaricanos dos que temos noticia, viviron por estas terras fai catro mil cincocentos anos aproximadamente.\nNa zona de Corbeira, en M\u00e1moas, en Val, na Legua de Beba, na Picota, etc., at\u00f3panse as primeiras follas da humanizaci\u00f3n de Mazaricos.\nSon os chamados d\u00f3lmenes ou m\u00e1moas, na s\u00faa maior\u00eda sen escavar, ag\u00e1s o de Parxubeira, que nos facilitou datos moi interesantes sobre aquees tempos.  <\/p>\n\n<p>Na parroquia de Eir\u00f3n, moi cerca da aldea de Corbeira, at\u00f3pase este importante complexo, de ata cinco d\u00f3lmenes, nos que se fixeron prospecci\u00f3ns arqueol\u00f3xicas con resultados moi aclaratorios sobre a vida dos nosos veci\u00f1os fai catro mil cincocentos anos.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.turismo.gal\/recurso\/-\/detalle\/17287\/dolmen-de-a-mina-de-perxubeira?langId=es_ES\" target=\"_blank\" rel=\"noopener\">Turismo de Galicia<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Polos restos arqueol\u00f3xicos atopados, podemos dicir que os primeiros mazaricanos dos que temos noticia, viviron por estas terras fai catro mil cincocentos anos aproximadamente. Na zona de Corbeira, en M\u00e1moas, en Val, na Legua de Beba, na Picota, etc., at\u00f3panse as primeiras follas da humanizaci\u00f3n de Mazaricos. Son os chamados d\u00f3lmenes ou m\u00e1moas, na s\u00faa [&hellip;]<\/p>\n","protected":false},"featured_media":13977,"template":"","concellos-contenido":[313],"categorias-contenido":[253],"class_list":["post-63468","contenido","type-contenido","status-publish","has-post-thumbnail","hentry","concellos-contenido-mazaricos-gl","categorias-contenido-megalitismo-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido\/63468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/contenido"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/13977"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=63468"}],"wp:term":[{"taxonomy":"concellos-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/concellos-contenido?post=63468"},{"taxonomy":"categorias-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categorias-contenido?post=63468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}