{"id":63191,"date":"2024-07-12T21:27:31","date_gmt":"2024-07-12T19:27:31","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/post\/razo-carballo"},"modified":"2025-01-07T13:40:27","modified_gmt":"2025-01-07T12:40:27","slug":"razo-carballo","status":"publish","type":"contenido","link":"https:\/\/visitacostadamorte.com\/gl\/post\/razo-carballo","title":{"rendered":"Razo (Carballo)"},"content":{"rendered":"<p>Esta \u00e9 unha das praias mellor valoradas para o surf en Galicia.<br \/>\nAdquiriu a s\u00faa fama pola calidade das s\u00faas olas durante todo o ano; longas e consistentes.<br \/>\nAdemais, \u00e9 unha praia apta para distintos graos de experiencia, xa que presenta picos para todos os niveis, polo que \u00e9 perfecta para calquera persoa que queira aprender.<br \/>\nOutra das s\u00faas maiores vangas \u00e9 que funciona tanto con marea baixa como con marea alta.<br \/>\nAqu\u00ed establ\u00e9cense algunhas das escolas de surf de maior prestixio.    <\/p>\n\n<p>Consulta <a href=\"https:\/\/es.surf-forecast.com\/breaks\/Playade-Razo\/forecasts\/latest\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>aqu\u00ed a previsi\u00f3n de olas para esta praia.<\/strong><\/a><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta \u00e9 unha das praias mellor valoradas para o surf en Galicia. Adquiriu a s\u00faa fama pola calidade das s\u00faas olas durante todo o ano; longas e consistentes. Ademais, \u00e9 unha praia apta para distintos graos de experiencia, xa que presenta picos para todos os niveis, polo que \u00e9 perfecta para calquera persoa que queira [&hellip;]<\/p>\n","protected":false},"featured_media":18053,"template":"","concellos-contenido":[331],"categorias-contenido":[265],"class_list":["post-63191","contenido","type-contenido","status-publish","has-post-thumbnail","hentry","concellos-contenido-carballo-gl","categorias-contenido-surf-playas-salvajes-gl"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido\/63191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/contenido"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/18053"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=63191"}],"wp:term":[{"taxonomy":"concellos-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/concellos-contenido?post=63191"},{"taxonomy":"categorias-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categorias-contenido?post=63191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}