{"id":63135,"date":"2024-09-16T19:04:46","date_gmt":"2024-09-16T17:04:46","guid":{"rendered":"https:\/\/great-goldberg.213-199-36-195.plesk.page\/post\/asalto-ao-castelo-de-vimianzo"},"modified":"2024-09-17T19:42:20","modified_gmt":"2024-09-17T17:42:20","slug":"asalto-ao-castelo-de-vimianzo","status":"publish","type":"contenido","link":"https:\/\/visitacostadamorte.com\/gl\/post\/asalto-ao-castelo-de-vimianzo","title":{"rendered":"Asalto ao Castelo de Vimianzo"},"content":{"rendered":"\n<p>No ano 1468 levouse a cabo en Galicia o que popularmente se co\u00f1ece como a revolta <em>irmandi\u00f1a<\/em>.\nEsta foi unha rebeli\u00f3n do pobo chano contra os altos estamentos da sociedade.\nUn fito hist\u00f3rico que se homenaxea cada ano en Vimianzo con la fiesta medieval del &#8220;Asalto ao Castelo&#8221;.\nNela poder\u00e1s percorrer as r\u00faas deste pobo que se viste de \u00e9poca para transportarte ao pasado mediante os &#8220;pinchos irmandi\u00f1os&#8221; que ofrecen a maior\u00eda de locais, os postos da feira medieval nos que te ser\u00e1 posible atopar produtos artesanais, pero sobre todo o asalto ao castillo, unha representaci\u00f3n teatral na que ter\u00e1s a oportunidade de converterte en revolucionario medieval.\nTodo iso acompa\u00f1ado de actuaci\u00f3ns musicais de artistas reco\u00f1ecidos a nivel nacional e internacional.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>No ano 1468 levouse a cabo en Galicia o que popularmente se co\u00f1ece como a revolta irmandi\u00f1a. Esta foi unha rebeli\u00f3n do pobo chano contra os altos estamentos da sociedade. Un fito hist\u00f3rico que se homenaxea cada ano en Vimianzo con la fiesta medieval del &#8220;Asalto ao Castelo&#8221;. Nela poder\u00e1s percorrer as r\u00faas deste pobo [&hellip;]<\/p>\n","protected":false},"featured_media":62343,"template":"","concellos-contenido":[329],"categorias-contenido":[623],"class_list":["post-63135","contenido","type-contenido","status-publish","has-post-thumbnail","hentry","concellos-contenido-vimianzo-gl","categorias-contenido-festas-de-interese-cultural"],"_links":{"self":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido\/63135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/contenido"}],"about":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/types\/contenido"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media\/62343"}],"wp:attachment":[{"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/media?parent=63135"}],"wp:term":[{"taxonomy":"concellos-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/concellos-contenido?post=63135"},{"taxonomy":"categorias-contenido","embeddable":true,"href":"https:\/\/visitacostadamorte.com\/gl\/wp-json\/wp\/v2\/categorias-contenido?post=63135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}